{"id":6536,"date":"2022-02-18T11:35:02","date_gmt":"2022-02-18T10:35:02","guid":{"rendered":"https:\/\/krasspluswissing.ernst-werbeagentur.dev\/?page_id=6536"},"modified":"2023-09-08T10:33:05","modified_gmt":"2023-09-08T08:33:05","slug":"about-us","status":"publish","type":"page","link":"https:\/\/krasspluswissing.de\/en\/about-us\/","title":{"rendered":"About us"},"content":{"rendered":"\n\n\n\n<!-- Block-Wrapper Anfang -->\n<div id=\"header-2col-block_d83dc4c11e1373633cf926a86cf284c5\" class=\"block block--header-2col parallax       \">\n  <div class=\" block__inner block__inner--header-2col py-3 py-md-5 \">\n<!-- \/Block-Wrapper Anfang -->\n\n    <div class=\"container\">\n      <div class=\"row\">\n        <div class=\"col-12 col-lg-6 pb-3 pb-lg-0\">\n          \n<div class=\"content__modul content__text\">\n  <h1>About us<\/h1>\n<p>In 1958, the families Krass and Wissing founded the company in the middle of a region called <em>M\u00fcnsterland<\/em>.<\/p>\n<p>Now in its third generation, <strong>Krass + Wissing<\/strong> has become a leading international company for cutted bindings and edging tapes.<\/p>\n<\/div>\n        <\/div>\n        <div class=\"col-12 col-lg-6 pb-0\">\n          <div class=\"header__img\">\n                      <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\n<!-- Block-Wrapper Ende -->\n  <\/div><!-- .block__inner -->\n<\/div><!-- .block -->\n<!-- \/Block-Wrapper Ende -->\n\n\n\n\n\n  <style type=\"text\/css\">\n    \/* H\u00f6he *\/\n    #header-2col-block_d83dc4c11e1373633cf926a86cf284c5 .block__inner--header-2col{\n              min-height: 87vh;\n          }\n\n    #header-2col-block_d83dc4c11e1373633cf926a86cf284c5.parallax{\n      height: calc(87vh - 100px);\n    }\n\n    @media only screen and (max-width: 991.98px) {\n      #header-2col-block_d83dc4c11e1373633cf926a86cf284c5.parallax{\n        height: 100vh;\n      }\n    }\n    @media only screen and (max-width: 575.98px) {\n      #header-2col-block_d83dc4c11e1373633cf926a86cf284c5.parallax{\n        height: calc(100vh - 125px);\n      }\n    }\n\n\n          \n      \n      \n      \n          \n    \n    \/* Hintergrundbild *\/\n          #header-2col-block_d83dc4c11e1373633cf926a86cf284c5 {\n        background-image: url(https:\/\/krasspluswissing.de\/wp-content\/uploads\/2022\/04\/Krass-Wissing-Kleber-Beschichten-Leim-Falzband.jpg);\n        background-size: cover;\n        background-position: center center;\n      }\n    \n    \/* Navigationshintergrund und Verlauf *\/\n    \n\n                  #header-2col-block_d83dc4c11e1373633cf926a86cf284c5 .block__inner {background: linear-gradient(to right, rgba(30,27,24, 0.8), rgba(0, 0, 0, 0))}\n          \n    #header-2col-block_d83dc4c11e1373633cf926a86cf284c5{      background-color: #FFFFFF;      color: #ffffff;    }                  <\/style>\n\n\n\n  <div class=\"diagonal diagonal--above diagonal--content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3\"><\/div>\n\n<!-- Block-Wrapper Anfang -->\n<div id=\"content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3\" class=\"block block--content-2col  pt-5 pb-1       \">\n    <div class=\"block__inner block__inner--content-2col container \">\n    <!-- \/Block-Wrapper Anfang -->\n\n\n\n        <div class=\"content row  justify-content-between\">\n          <div class=\"content__spalte content__spalte--1 col-12 col-lg-8 pb-3 pb-lg-0\">\n            \n<div class=\"content__modul content__text\">\n  <h2>Good service with over 60 years experience<\/h2>\n<p>&nbsp;<\/p>\n<p>Founded in 1958 by Norbert Wissing and Peter-Paul Krass sen., at first under the name of their wives, as the company <strong>Hildegard Krass Schr\u00e4gb\u00e4nder<\/strong>, we have never lost our roots in the M\u00fcnsterland region.<\/p>\n<p>After several locational changes, and now in the transition to the third generation, we at Krass + Wissing are proud to be able to deliver our products from Steinfurt to the whole world.<\/p>\n<\/div>\n          <\/div>\n          <div class=\"content__spalte content__spalte--2 col-12 col-lg-4 pb-0\">\n                      <\/div>\n        <\/div>\n\n\n<!-- Block-Wrapper Ende -->\n      <\/div><!-- .block__inner -->\n<\/div><!-- .block -->\n<!-- \/Block-Wrapper Ende -->\n\n\n  <style type=\"text\/css\">\n    #content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3{      background-color: #777777;      color: #ffffff;    }        #content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3 a{ color: #a11f30;}          #content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3 .button { background-color: #a11f30;\n                                       border-color: #a11f30 }\n      #content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3 .button a, #content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3 .field-wrap input[type=button] { color: #FFFFFF !important }\n      #content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3 .button:hover a, #content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3 .field-wrap input[type=button]:hover { color: #a11f30 !important }\n      #content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3 .button--2:after { color: #a11f30 }\n      #content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3 .button--3:before { border-color: #a11f30 !important }\n                \n            .diagonal--content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3  { background-color: #777777 }\n    \n    #content-2col-block_5e429d63cf0d09c22dcd980b2a4d95f3{ z-index: 1 }\n  <\/style>\n\n\n\n\n<!-- Block-Wrapper Anfang -->\n<div id=\"content-2col-block_1110f795104ac36d7584b9e791b7476b\" class=\"block block--content-2col  pt-1 pb-5       \">\n    <div class=\"block__inner block__inner--content-2col container \">\n    <!-- \/Block-Wrapper Anfang -->\n\n\n\n        <div class=\"content row  justify-content-between\">\n          <div class=\"content__spalte content__spalte--1 col-12 col-lg-4 pb-3 pb-lg-0\">\n                      <\/div>\n          <div class=\"content__spalte content__spalte--2 col-12 col-lg-8 pb-0\">\n            \n<div class=\"content__modul content__text\">\n  <p>As an established family business, our ties to our region are just as important to us as the responsible treatment of our employees and our environment.<\/p>\n<p>Tradition and innovation has made us what we are today.<\/p>\n<\/div>\n          <\/div>\n        <\/div>\n\n\n<!-- Block-Wrapper Ende -->\n      <\/div><!-- .block__inner -->\n<\/div><!-- .block -->\n<!-- \/Block-Wrapper Ende -->\n\n  <div class=\"diagonal diagonal--below diagonal--content-2col-block_1110f795104ac36d7584b9e791b7476b\"><\/div>\n\n  <style type=\"text\/css\">\n    #content-2col-block_1110f795104ac36d7584b9e791b7476b{      background-color: #777777;      color: #ffffff;    }        #content-2col-block_1110f795104ac36d7584b9e791b7476b a{ color: #a11f30;}          #content-2col-block_1110f795104ac36d7584b9e791b7476b .button { background-color: #a11f30;\n                                       border-color: #a11f30 }\n      #content-2col-block_1110f795104ac36d7584b9e791b7476b .button a, #content-2col-block_1110f795104ac36d7584b9e791b7476b .field-wrap input[type=button] { color: #FFFFFF !important }\n      #content-2col-block_1110f795104ac36d7584b9e791b7476b .button:hover a, #content-2col-block_1110f795104ac36d7584b9e791b7476b .field-wrap input[type=button]:hover { color: #a11f30 !important }\n      #content-2col-block_1110f795104ac36d7584b9e791b7476b .button--2:after { color: #a11f30 }\n      #content-2col-block_1110f795104ac36d7584b9e791b7476b .button--3:before { border-color: #a11f30 !important }\n                \n            .diagonal--content-2col-block_1110f795104ac36d7584b9e791b7476b  { background-color: #777777 }\n    \n    #content-2col-block_1110f795104ac36d7584b9e791b7476b{ z-index: 1 }\n  <\/style>\n\n\n\n<!-- Block-Wrapper Anfang -->\n<div id=\"header-fullscreen-block_e71d05edaccbb5ff452650df66aa3bf4\" class=\"block block--header-fullscreen        \" >\n  <div class=\" block__inner block__inner--header-fullscreen \">\n<!-- \/Block-Wrapper Anfang -->\n\n    \n            <div class=\"header\">\n                              <img decoding=\"async\" src=\"https:\/\/krasspluswissing.de\/wp-content\/uploads\/2022\/06\/krass-wissing-timeline-alte-falzmaschine.jpg\" alt=\"Alte Falzmaschinen Krass+Wissing Anf\u00e4nge\">\n                          <\/div>\n\n          \n\n<!-- Block-Wrapper Ende -->\n  <\/div><!-- .block__inner -->\n<\/div><!-- .block -->\n<!-- \/Block-Wrapper Ende -->\n\n\n  \n\n  <script>\n  jQuery( document ).ready(function() {\n    headerSlider();\n  })\n\n  function headerSlider(){\n\n    jQuery('.imageslider__inner').slick({\n      dots: true,\n      infinite: true,\n      speed: 1750,\n      appendArrows: false,\n      autoplay: true,\n      touchThreshold: 20,\n      draggable: true,\n      autoplaySpeed: 3000    });\n\n  }\n\n  <\/script>\n\n  <style type=\"text\/css\">\n  \/* H\u00f6he *\/\n      #header-fullscreen-block_e71d05edaccbb5ff452650df66aa3bf4 .block__inner--header-fullscreen img, #header-fullscreen-block_e71d05edaccbb5ff452650df66aa3bf4 .block__inner--header-fullscreen .acf-map {\n              height: 70vh;\n          }\n    #header-fullscreen-block_e71d05edaccbb5ff452650df66aa3bf4 .block__inner--header-fullscreen .parallax-window {\n              min-height: 70vh;\n          }\n  \n  \n  \n  \n  \n  \n  \/* Navigationshintergrund und Verlauf *\/\n  \n  \/* Ausrichtung *\/\n  #header-fullscreen-block_e71d05edaccbb5ff452650df66aa3bf4 .block__inner--header-fullscreen img {\n    object-position: 50% 50%;\n  }\n\n  #header-fullscreen-block_e71d05edaccbb5ff452650df66aa3bf4{ z-index: -1 }\n  <\/style>\n\n\n\n\n  <div class=\"diagonal diagonal--above  diagonal--kpw-timeline-block_db65300e207c7b33a79f77705e7b9fb7\"><\/div>\n\n<!-- Block-Wrapper Anfang -->\n<div id=\"kpw-timeline-block_db65300e207c7b33a79f77705e7b9fb7\" class=\"block block--kpw-timeline pt-0 pb-0       \">\n  <div class=\"block__inner block__inner--kpw-timeline container \">\n    <!-- \/Block-Wrapper Anfang -->\n\n\n\n\n\n\n<div class=\"ag-timeline-block\">\n  <section class=\"ag-section\">\n    <div class=\"container\">\n      <div class=\"js-timeline ag-timeline\">\n        <div class=\"js-timeline_line ag-timeline_line\">\n          <div class=\"js-timeline_line-progress ag-timeline_line-progress\"><\/div>\n        <\/div>\n        <div class=\"ag-timeline_list\">\n\n          \n\n            <div class=\"js-timeline_item ag-timeline_item\">\n              <div class=\"ag-timeline-card_box\">\n                <div class=\"js-timeline-card_point-box ag-timeline-card_point-box\">\n                  <div class=\"ag-timeline-card_point\"><span>1958<\/span><\/div>\n                <\/div>\n              <\/div>\n              <div class=\"ag-timeline-card_item\">\n                <div class=\"ag-timeline-card_inner\">\n                                      <div class=\"ag-timeline-card_img-box\">\n                      <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/krasspluswissing.de\/wp-content\/uploads\/2022\/06\/krass-wissing-timeline-1958.jpg\" class=\"ag-timeline-card_img\" alt=\"\" width=\"640\" height=\"360\" \/>\n                    <\/div>\n                  \n                  <div class=\"ag-timeline-card_info\">\n                    <div class=\"ag-timeline-card_meta\">\n                      1958                    <\/div>\n                    <div class=\"ag-timeline-card_desc\">\n                      <p>Norbert Wissing and Peter-Paul Krass, together with their wives, found the company <strong>Hildegard Krass Schr\u00e4gb\u00e4nder<\/strong><\/p>\n                    <\/div>\n                  <\/div>\n                <\/div>\n                <div class=\"ag-timeline-card_arrow\"><\/div>\n              <\/div>\n            <\/div>\n\n\n\n          \n\n            <div class=\"js-timeline_item ag-timeline_item\">\n              <div class=\"ag-timeline-card_box\">\n                <div class=\"js-timeline-card_point-box ag-timeline-card_point-box\">\n                  <div class=\"ag-timeline-card_point\"><span>1963<\/span><\/div>\n                <\/div>\n              <\/div>\n              <div class=\"ag-timeline-card_item\">\n                <div class=\"ag-timeline-card_inner\">\n                  \n                  <div class=\"ag-timeline-card_info\">\n                    <div class=\"ag-timeline-card_meta\">\n                      1963                    <\/div>\n                    <div class=\"ag-timeline-card_desc\">\n                      <p>the move to Steinfurt-Borghorst and the first employees are hired<\/p>\n                    <\/div>\n                  <\/div>\n                <\/div>\n                <div class=\"ag-timeline-card_arrow\"><\/div>\n              <\/div>\n            <\/div>\n\n\n\n          \n\n            <div class=\"js-timeline_item ag-timeline_item\">\n              <div class=\"ag-timeline-card_box\">\n                <div class=\"js-timeline-card_point-box ag-timeline-card_point-box\">\n                  <div class=\"ag-timeline-card_point\"><span>1988<\/span><\/div>\n                <\/div>\n              <\/div>\n              <div class=\"ag-timeline-card_item\">\n                <div class=\"ag-timeline-card_inner\">\n                                      <div class=\"ag-timeline-card_img-box\">\n                      <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/krasspluswissing.de\/wp-content\/uploads\/2022\/06\/krass-wissing-timeline-1988.jpg\" class=\"ag-timeline-card_img\" alt=\"Michael Wissing Krass+Wissing\" width=\"640\" height=\"360\" \/>\n                    <\/div>\n                  \n                  <div class=\"ag-timeline-card_info\">\n                    <div class=\"ag-timeline-card_meta\">\n                      1988                    <\/div>\n                    <div class=\"ag-timeline-card_desc\">\n                      <p>Michael Wissing joins his parents&#8217; company.<\/p>\n                    <\/div>\n                  <\/div>\n                <\/div>\n                <div class=\"ag-timeline-card_arrow\"><\/div>\n              <\/div>\n            <\/div>\n\n\n\n          \n\n            <div class=\"js-timeline_item ag-timeline_item\">\n              <div class=\"ag-timeline-card_box\">\n                <div class=\"js-timeline-card_point-box ag-timeline-card_point-box\">\n                  <div class=\"ag-timeline-card_point\"><span>1990<\/span><\/div>\n                <\/div>\n              <\/div>\n              <div class=\"ag-timeline-card_item\">\n                <div class=\"ag-timeline-card_inner\">\n                                      <div class=\"ag-timeline-card_img-box\">\n                      <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/krasspluswissing.de\/wp-content\/uploads\/2022\/06\/krass-wissing-timeline-1990.jpg\" class=\"ag-timeline-card_img\" alt=\"\" width=\"640\" height=\"360\" \/>\n                    <\/div>\n                  \n                  <div class=\"ag-timeline-card_info\">\n                    <div class=\"ag-timeline-card_meta\">\n                      1990                    <\/div>\n                    <div class=\"ag-timeline-card_desc\">\n                      <p>in april the entry of Peter Krass will follow<\/p>\n                    <\/div>\n                  <\/div>\n                <\/div>\n                <div class=\"ag-timeline-card_arrow\"><\/div>\n              <\/div>\n            <\/div>\n\n\n\n          \n\n            <div class=\"js-timeline_item ag-timeline_item\">\n              <div class=\"ag-timeline-card_box\">\n                <div class=\"js-timeline-card_point-box ag-timeline-card_point-box\">\n                  <div class=\"ag-timeline-card_point\"><span>1992<\/span><\/div>\n                <\/div>\n              <\/div>\n              <div class=\"ag-timeline-card_item\">\n                <div class=\"ag-timeline-card_inner\">\n                                      <div class=\"ag-timeline-card_img-box\">\n                      <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/krasspluswissing.de\/wp-content\/uploads\/2022\/06\/krass-wissing-timeline-1992.jpg\" class=\"ag-timeline-card_img\" alt=\"Geb\u00e4ude Krass+Wissing Schoppenkamp Wilmsbergerweg\" width=\"640\" height=\"360\" \/>\n                    <\/div>\n                  \n                  <div class=\"ag-timeline-card_info\">\n                    <div class=\"ag-timeline-card_meta\">\n                      1992                    <\/div>\n                    <div class=\"ag-timeline-card_desc\">\n                      <p>Construction of a new company building begins on Wilmsberger Weg<\/p>\n                    <\/div>\n                  <\/div>\n                <\/div>\n                <div class=\"ag-timeline-card_arrow\"><\/div>\n              <\/div>\n            <\/div>\n\n\n\n          \n\n            <div class=\"js-timeline_item ag-timeline_item\">\n              <div class=\"ag-timeline-card_box\">\n                <div class=\"js-timeline-card_point-box ag-timeline-card_point-box\">\n                  <div class=\"ag-timeline-card_point\"><span>2000<\/span><\/div>\n                <\/div>\n              <\/div>\n              <div class=\"ag-timeline-card_item\">\n                <div class=\"ag-timeline-card_inner\">\n                                      <div class=\"ag-timeline-card_img-box\">\n                      <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/krasspluswissing.de\/wp-content\/uploads\/2022\/06\/krass-wissing-timeline-2000.jpg\" class=\"ag-timeline-card_img\" alt=\"Logo M\u00e4nnchen Krass+Wissing seit 2000\" width=\"640\" height=\"360\" \/>\n                    <\/div>\n                  \n                  <div class=\"ag-timeline-card_info\">\n                    <div class=\"ag-timeline-card_meta\">\n                      2000                    <\/div>\n                    <div class=\"ag-timeline-card_desc\">\n                      <p>the change of name to <strong>Krass + Wissing GmbH<\/strong><\/p>\n                    <\/div>\n                  <\/div>\n                <\/div>\n                <div class=\"ag-timeline-card_arrow\"><\/div>\n              <\/div>\n            <\/div>\n\n\n\n          \n\n            <div class=\"js-timeline_item ag-timeline_item\">\n              <div class=\"ag-timeline-card_box\">\n                <div class=\"js-timeline-card_point-box ag-timeline-card_point-box\">\n                  <div class=\"ag-timeline-card_point\"><span>2002<\/span><\/div>\n                <\/div>\n              <\/div>\n              <div class=\"ag-timeline-card_item\">\n                <div class=\"ag-timeline-card_inner\">\n                                      <div class=\"ag-timeline-card_img-box\">\n                      <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/krasspluswissing.de\/wp-content\/uploads\/2022\/06\/krass-wissing-timeline-2002.jpg\" class=\"ag-timeline-card_img\" alt=\"Steinfurt Steinfurter Ei Webereistrasse Krass+Wissing Modell des Geb\u00e4udes\" width=\"640\" height=\"360\" \/>\n                    <\/div>\n                  \n                  <div class=\"ag-timeline-card_info\">\n                    <div class=\"ag-timeline-card_meta\">\n                      2002                    <\/div>\n                    <div class=\"ag-timeline-card_desc\">\n                      <p>The company moves to new facilities on Webereistrasse, which are expanded again and again in the following years.<\/p>\n                    <\/div>\n                  <\/div>\n                <\/div>\n                <div class=\"ag-timeline-card_arrow\"><\/div>\n              <\/div>\n            <\/div>\n\n\n\n          \n\n            <div class=\"js-timeline_item ag-timeline_item\">\n              <div class=\"ag-timeline-card_box\">\n                <div class=\"js-timeline-card_point-box ag-timeline-card_point-box\">\n                  <div class=\"ag-timeline-card_point\"><span>2019<\/span><\/div>\n                <\/div>\n              <\/div>\n              <div class=\"ag-timeline-card_item\">\n                <div class=\"ag-timeline-card_inner\">\n                  \n                  <div class=\"ag-timeline-card_info\">\n                    <div class=\"ag-timeline-card_meta\">\n                      2019                    <\/div>\n                    <div class=\"ag-timeline-card_desc\">\n                      <p>Paul Krass joins the company and thus initiates the transition to the third generation.<\/p>\n                    <\/div>\n                  <\/div>\n                <\/div>\n                <div class=\"ag-timeline-card_arrow\"><\/div>\n              <\/div>\n            <\/div>\n\n\n\n          \n        <\/div>\n      <\/div>\n    <\/div>\n  <\/section>\n<\/div>\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n<!-- Block-Wrapper Ende -->\n      <\/div><!-- .block__inner -->\n<\/div><!-- .block -->\n<!-- \/Block-Wrapper Ende -->\n\n\n\n\n\n\n\n\n\n\n\n  <style type=\"text\/css\">\n    #kpw-timeline-block_db65300e207c7b33a79f77705e7b9fb7{      background-color: #FFFFFF;          }                \n            .diagonal--kpw-timeline-block_db65300e207c7b33a79f77705e7b9fb7  { background-color: #FFFFFF }\n    \n    \n    #kpw-timeline-block_db65300e207c7b33a79f77705e7b9fb7{ z-index:  }\n  <\/style>\n\n\n\n  <div class=\"diagonal diagonal--above diagonal--content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258\"><\/div>\n\n<!-- Block-Wrapper Anfang -->\n<div id=\"content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258\" class=\"block block--content-2col  pt-5 pb-5       \">\n    <div class=\"block__inner block__inner--content-2col container \">\n    <!-- \/Block-Wrapper Anfang -->\n\n\n\n        <div class=\"content row align-items-center justify-content-between\">\n          <div class=\"content__spalte content__spalte--1 col-12 col-lg-5 pb-3 pb-lg-0\">\n            \n<div class=\"content__modul content__text\">\n  <h3>Products<\/h3>\n<p>Our products are your products. Take advantage of our processes and our know-how &#8211; together we develop the ideal product for your application.<\/p>\n<p>Whether with your own materials or ours, our primary goal is to optimize your process, increase quality and minimize downtime.<\/p>\n<p><a class=\"link__arrow\" href=\"https:\/\/krasspluswissing.de\/produkte\/\">to the products<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n          <\/div>\n          <div class=\"content__spalte content__spalte--2 col-12 col-lg-5 pb-0\">\n            \n<div class=\"content__modul content__text\">\n  <h3>Materials<\/h3>\n<p>We find or design the ideal material for your product \u2013 individually adapted to your needs. Our unique product range has been developed in over 60 years of close cooperation with a wide range of industries.<\/p>\n<p><a class=\"link__arrow\" href=\"https:\/\/krasspluswissing.de\/materialien\/\">to the materials<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n          <\/div>\n        <\/div>\n\n\n<!-- Block-Wrapper Ende -->\n      <\/div><!-- .block__inner -->\n<\/div><!-- .block -->\n<!-- \/Block-Wrapper Ende -->\n\n\n  <style type=\"text\/css\">\n    #content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258{      background-color: #777777;      color: #ffffff;    }        #content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258 a{ color: #ffffff;}          #content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258 .button { background-color: #ffffff;\n                                       border-color: #ffffff }\n      #content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258 .button a, #content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258 .field-wrap input[type=button] { color: #FFFFFF !important }\n      #content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258 .button:hover a, #content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258 .field-wrap input[type=button]:hover { color: #ffffff !important }\n      #content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258 .button--2:after { color: #ffffff }\n      #content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258 .button--3:before { border-color: #ffffff !important }\n                \n            .diagonal--content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258  { background-color: #777777 }\n    \n    #content-2col-block_a98dc5851d389ecf0128ae3f9e1ee258{ z-index: 1 }\n  <\/style>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"protect_children":false,"_relevanssi_hide_post":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-6536","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Color chart archive<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/krasspluswissing.de\/en\/about-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About us\" \/>\n<meta property=\"og:url\" content=\"https:\/\/krasspluswissing.de\/en\/about-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Krass + Wissing\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-08T08:33:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/about-us\\\/\",\"url\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/about-us\\\/\",\"name\":\"Color chart archive\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/#website\"},\"datePublished\":\"2022-02-18T10:35:02+00:00\",\"dateModified\":\"2023-09-08T08:33:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/about-us\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/about-us\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/about-us\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/\",\"name\":\"Krass + Wissing\",\"description\":\"Textile B\u00e4nder\",\"publisher\":{\"@id\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/#organization\"},\"alternateName\":\"Krass & Wissing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/#organization\",\"name\":\"Krass+Wissing\",\"alternateName\":\"Krass&Wissing\",\"url\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/krasspluswissing.de\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/KW_Logo_since_1958.png\",\"contentUrl\":\"https:\\\/\\\/krasspluswissing.de\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/KW_Logo_since_1958.png\",\"width\":1684,\"height\":378,\"caption\":\"Krass+Wissing\"},\"image\":{\"@id\":\"https:\\\/\\\/krasspluswissing.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Color chart archive","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/krasspluswissing.de\/en\/about-us\/","og_locale":"en_US","og_type":"article","og_title":"About us","og_url":"https:\/\/krasspluswissing.de\/en\/about-us\/","og_site_name":"Krass + Wissing","article_modified_time":"2023-09-08T08:33:05+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/krasspluswissing.de\/en\/about-us\/","url":"https:\/\/krasspluswissing.de\/en\/about-us\/","name":"Color chart archive","isPartOf":{"@id":"https:\/\/krasspluswissing.de\/en\/#website"},"datePublished":"2022-02-18T10:35:02+00:00","dateModified":"2023-09-08T08:33:05+00:00","breadcrumb":{"@id":"https:\/\/krasspluswissing.de\/en\/about-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/krasspluswissing.de\/en\/about-us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/krasspluswissing.de\/en\/about-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/krasspluswissing.de\/en\/"},{"@type":"ListItem","position":2,"name":"About us"}]},{"@type":"WebSite","@id":"https:\/\/krasspluswissing.de\/en\/#website","url":"https:\/\/krasspluswissing.de\/en\/","name":"Krass + Wissing","description":"Textile B\u00e4nder","publisher":{"@id":"https:\/\/krasspluswissing.de\/en\/#organization"},"alternateName":"Krass & Wissing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/krasspluswissing.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/krasspluswissing.de\/en\/#organization","name":"Krass+Wissing","alternateName":"Krass&Wissing","url":"https:\/\/krasspluswissing.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/krasspluswissing.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/krasspluswissing.de\/wp-content\/uploads\/2022\/10\/KW_Logo_since_1958.png","contentUrl":"https:\/\/krasspluswissing.de\/wp-content\/uploads\/2022\/10\/KW_Logo_since_1958.png","width":1684,"height":378,"caption":"Krass+Wissing"},"image":{"@id":"https:\/\/krasspluswissing.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/krasspluswissing.de\/en\/wp-json\/wp\/v2\/pages\/6536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/krasspluswissing.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/krasspluswissing.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/krasspluswissing.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/krasspluswissing.de\/en\/wp-json\/wp\/v2\/comments?post=6536"}],"version-history":[{"count":0,"href":"https:\/\/krasspluswissing.de\/en\/wp-json\/wp\/v2\/pages\/6536\/revisions"}],"wp:attachment":[{"href":"https:\/\/krasspluswissing.de\/en\/wp-json\/wp\/v2\/media?parent=6536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}